{"id":2945,"date":"2023-07-13T10:50:14","date_gmt":"2023-07-13T10:50:14","guid":{"rendered":"https:\/\/radiocityvalencia.es\/?post_type=eventos&#038;p=2945"},"modified":"2023-09-04T10:23:51","modified_gmt":"2023-09-04T10:23:51","slug":"trinity-roots-6-09-2023","status":"publish","type":"eventos","link":"https:\/\/radiocityvalencia.es\/en\/eventos\/trinity-roots-6-09-2023\/","title":{"rendered":"Trinity Roots 6\/09\/2023"},"author":3,"featured_media":2870,"parent":0,"template":"","meta":[],"class_list":["post-2945","eventos","type-eventos","status-publish","has-post-thumbnail","estilo-dj","estilo-dub","estilo-reggae"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Trinity Roots 6\/09\/2023 - Radiocity<\/title>\n<meta name=\"description\" content=\"El DJ residente de la crew de Bam Bam Entertaiment tras los conciertos de la O.G. Reggae Session es Trinity Roots. Fabi\u00e1n lleva afincado en valencia desde hace muchos a\u00f1os, es originario de Costa Rica y uno de los principales activos de la Dub Music y el Reggae en Valencia. Ha pinchado pr\u00e1cticamente en todas las salas de la ciudad y como promotor y miembro de varios colectivos enfocados a las m\u00fasica jamaicana y derivados. Un seguro infalible en cabina para rematar los mi\u00e9rcoles en Radio City Valencia.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/radiocityvalencia.es\/en\/eventos\/trinity-roots-6-09-2023\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Trinity Roots 6\/09\/2023 - Radiocity\" \/>\n<meta property=\"og:description\" content=\"El DJ residente de la crew de Bam Bam Entertaiment tras los conciertos de la O.G. Reggae Session es Trinity Roots. Fabi\u00e1n lleva afincado en valencia desde hace muchos a\u00f1os, es originario de Costa Rica y uno de los principales activos de la Dub Music y el Reggae en Valencia. Ha pinchado pr\u00e1cticamente en todas las salas de la ciudad y como promotor y miembro de varios colectivos enfocados a las m\u00fasica jamaicana y derivados. Un seguro infalible en cabina para rematar los mi\u00e9rcoles en Radio City Valencia.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/radiocityvalencia.es\/en\/eventos\/trinity-roots-6-09-2023\/\" \/>\n<meta property=\"og:site_name\" content=\"Radiocity\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/radiocityvlc\" \/>\n<meta property=\"article:modified_time\" content=\"2023-09-04T10:23:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/radiocityvalencia.es\/wp-content\/uploads\/2023\/07\/Miniatura-DJ-Trinity.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"398\" \/>\n\t<meta property=\"og:image:height\" content=\"528\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/radiocityvalencia.es\\\/en\\\/eventos\\\/trinity-roots-6-09-2023\\\/\",\"url\":\"https:\\\/\\\/radiocityvalencia.es\\\/en\\\/eventos\\\/trinity-roots-6-09-2023\\\/\",\"name\":\"Trinity Roots 6\\\/09\\\/2023 - Radiocity\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/radiocityvalencia.es\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/radiocityvalencia.es\\\/en\\\/eventos\\\/trinity-roots-6-09-2023\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/radiocityvalencia.es\\\/en\\\/eventos\\\/trinity-roots-6-09-2023\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/radiocityvalencia.es\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/Miniatura-DJ-Trinity.webp\",\"datePublished\":\"2023-07-13T10:50:14+00:00\",\"dateModified\":\"2023-09-04T10:23:51+00:00\",\"description\":\"El DJ residente de la crew de Bam Bam Entertaiment tras los conciertos de la O.G. Reggae Session es Trinity Roots. Fabi\u00e1n lleva afincado en valencia desde hace muchos a\u00f1os, es originario de Costa Rica y uno de los principales activos de la Dub Music y el Reggae en Valencia. Ha pinchado pr\u00e1cticamente en todas las salas de la ciudad y como promotor y miembro de varios colectivos enfocados a las m\u00fasica jamaicana y derivados. Un seguro infalible en cabina para rematar los mi\u00e9rcoles en Radio City Valencia.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/radiocityvalencia.es\\\/en\\\/eventos\\\/trinity-roots-6-09-2023\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/radiocityvalencia.es\\\/en\\\/eventos\\\/trinity-roots-6-09-2023\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/radiocityvalencia.es\\\/en\\\/eventos\\\/trinity-roots-6-09-2023\\\/#primaryimage\",\"url\":\"https:\\\/\\\/radiocityvalencia.es\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/Miniatura-DJ-Trinity.webp\",\"contentUrl\":\"https:\\\/\\\/radiocityvalencia.es\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/Miniatura-DJ-Trinity.webp\",\"width\":398,\"height\":528},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/radiocityvalencia.es\\\/en\\\/eventos\\\/trinity-roots-6-09-2023\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/radiocityvalencia.es\\\/en\\\/home\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Eventos\",\"item\":\"https:\\\/\\\/radiocityvalencia.es\\\/en\\\/eventos\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Trinity Roots 6\\\/09\\\/2023\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/radiocityvalencia.es\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/radiocityvalencia.es\\\/en\\\/\",\"name\":\"Radio City Valencia\",\"description\":\"The Place to Be\",\"publisher\":{\"@id\":\"https:\\\/\\\/radiocityvalencia.es\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/radiocityvalencia.es\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/radiocityvalencia.es\\\/en\\\/#organization\",\"name\":\"Radio City Valencia\",\"url\":\"https:\\\/\\\/radiocityvalencia.es\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/radiocityvalencia.es\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/radiocityvalencia.es\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/LOGO_RADIO_WHT.png\",\"contentUrl\":\"https:\\\/\\\/radiocityvalencia.es\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/LOGO_RADIO_WHT.png\",\"width\":398,\"height\":57,\"caption\":\"Radio City Valencia\"},\"image\":{\"@id\":\"https:\\\/\\\/radiocityvalencia.es\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/radiocityvlc\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Trinity Roots 6\/09\/2023 - Radiocity","description":"El DJ residente de la crew de Bam Bam Entertaiment tras los conciertos de la O.G. Reggae Session es Trinity Roots. Fabi\u00e1n lleva afincado en valencia desde hace muchos a\u00f1os, es originario de Costa Rica y uno de los principales activos de la Dub Music y el Reggae en Valencia. Ha pinchado pr\u00e1cticamente en todas las salas de la ciudad y como promotor y miembro de varios colectivos enfocados a las m\u00fasica jamaicana y derivados. Un seguro infalible en cabina para rematar los mi\u00e9rcoles en Radio City Valencia.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/radiocityvalencia.es\/en\/eventos\/trinity-roots-6-09-2023\/","og_locale":"en_US","og_type":"article","og_title":"Trinity Roots 6\/09\/2023 - Radiocity","og_description":"El DJ residente de la crew de Bam Bam Entertaiment tras los conciertos de la O.G. Reggae Session es Trinity Roots. Fabi\u00e1n lleva afincado en valencia desde hace muchos a\u00f1os, es originario de Costa Rica y uno de los principales activos de la Dub Music y el Reggae en Valencia. Ha pinchado pr\u00e1cticamente en todas las salas de la ciudad y como promotor y miembro de varios colectivos enfocados a las m\u00fasica jamaicana y derivados. Un seguro infalible en cabina para rematar los mi\u00e9rcoles en Radio City Valencia.","og_url":"https:\/\/radiocityvalencia.es\/en\/eventos\/trinity-roots-6-09-2023\/","og_site_name":"Radiocity","article_publisher":"https:\/\/www.facebook.com\/radiocityvlc","article_modified_time":"2023-09-04T10:23:51+00:00","og_image":[{"width":398,"height":528,"url":"https:\/\/radiocityvalencia.es\/wp-content\/uploads\/2023\/07\/Miniatura-DJ-Trinity.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/radiocityvalencia.es\/en\/eventos\/trinity-roots-6-09-2023\/","url":"https:\/\/radiocityvalencia.es\/en\/eventos\/trinity-roots-6-09-2023\/","name":"Trinity Roots 6\/09\/2023 - Radiocity","isPartOf":{"@id":"https:\/\/radiocityvalencia.es\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/radiocityvalencia.es\/en\/eventos\/trinity-roots-6-09-2023\/#primaryimage"},"image":{"@id":"https:\/\/radiocityvalencia.es\/en\/eventos\/trinity-roots-6-09-2023\/#primaryimage"},"thumbnailUrl":"https:\/\/radiocityvalencia.es\/wp-content\/uploads\/2023\/07\/Miniatura-DJ-Trinity.webp","datePublished":"2023-07-13T10:50:14+00:00","dateModified":"2023-09-04T10:23:51+00:00","description":"El DJ residente de la crew de Bam Bam Entertaiment tras los conciertos de la O.G. Reggae Session es Trinity Roots. Fabi\u00e1n lleva afincado en valencia desde hace muchos a\u00f1os, es originario de Costa Rica y uno de los principales activos de la Dub Music y el Reggae en Valencia. Ha pinchado pr\u00e1cticamente en todas las salas de la ciudad y como promotor y miembro de varios colectivos enfocados a las m\u00fasica jamaicana y derivados. Un seguro infalible en cabina para rematar los mi\u00e9rcoles en Radio City Valencia.","breadcrumb":{"@id":"https:\/\/radiocityvalencia.es\/en\/eventos\/trinity-roots-6-09-2023\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/radiocityvalencia.es\/en\/eventos\/trinity-roots-6-09-2023\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/radiocityvalencia.es\/en\/eventos\/trinity-roots-6-09-2023\/#primaryimage","url":"https:\/\/radiocityvalencia.es\/wp-content\/uploads\/2023\/07\/Miniatura-DJ-Trinity.webp","contentUrl":"https:\/\/radiocityvalencia.es\/wp-content\/uploads\/2023\/07\/Miniatura-DJ-Trinity.webp","width":398,"height":528},{"@type":"BreadcrumbList","@id":"https:\/\/radiocityvalencia.es\/en\/eventos\/trinity-roots-6-09-2023\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/radiocityvalencia.es\/en\/home\/"},{"@type":"ListItem","position":2,"name":"Eventos","item":"https:\/\/radiocityvalencia.es\/en\/eventos\/"},{"@type":"ListItem","position":3,"name":"Trinity Roots 6\/09\/2023"}]},{"@type":"WebSite","@id":"https:\/\/radiocityvalencia.es\/en\/#website","url":"https:\/\/radiocityvalencia.es\/en\/","name":"Radio City Valencia","description":"The Place to Be","publisher":{"@id":"https:\/\/radiocityvalencia.es\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/radiocityvalencia.es\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/radiocityvalencia.es\/en\/#organization","name":"Radio City Valencia","url":"https:\/\/radiocityvalencia.es\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/radiocityvalencia.es\/en\/#\/schema\/logo\/image\/","url":"https:\/\/radiocityvalencia.es\/wp-content\/uploads\/2023\/02\/LOGO_RADIO_WHT.png","contentUrl":"https:\/\/radiocityvalencia.es\/wp-content\/uploads\/2023\/02\/LOGO_RADIO_WHT.png","width":398,"height":57,"caption":"Radio City Valencia"},"image":{"@id":"https:\/\/radiocityvalencia.es\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/radiocityvlc"]}]}},"_links":{"self":[{"href":"https:\/\/radiocityvalencia.es\/en\/wp-json\/wp\/v2\/eventos\/2945","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/radiocityvalencia.es\/en\/wp-json\/wp\/v2\/eventos"}],"about":[{"href":"https:\/\/radiocityvalencia.es\/en\/wp-json\/wp\/v2\/types\/eventos"}],"author":[{"embeddable":true,"href":"https:\/\/radiocityvalencia.es\/en\/wp-json\/wp\/v2\/users\/3"}],"version-history":[{"count":5,"href":"https:\/\/radiocityvalencia.es\/en\/wp-json\/wp\/v2\/eventos\/2945\/revisions"}],"predecessor-version":[{"id":3242,"href":"https:\/\/radiocityvalencia.es\/en\/wp-json\/wp\/v2\/eventos\/2945\/revisions\/3242"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/radiocityvalencia.es\/en\/wp-json\/wp\/v2\/media\/2870"}],"wp:attachment":[{"href":"https:\/\/radiocityvalencia.es\/en\/wp-json\/wp\/v2\/media?parent=2945"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}