{"id":1803,"date":"2023-03-31T18:34:53","date_gmt":"2023-03-31T18:34:53","guid":{"rendered":"https:\/\/radiocityvalencia.es\/?post_type=artistas&#038;p=1803"},"modified":"2023-10-30T13:03:09","modified_gmt":"2023-10-30T13:03:09","slug":"bearoid","status":"publish","type":"artistas","link":"https:\/\/radiocityvalencia.es\/en\/artistas\/bearoid\/","title":{"rendered":"Bearoid"},"author":2,"featured_media":1806,"parent":0,"template":"","meta":[],"class_list":["post-1803","artistas","type-artistas","status-publish","has-post-thumbnail","estilo_musical-pop"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Bearoid - Radiocity<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/radiocityvalencia.es\/en\/artistas\/bearoid\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bearoid - Radiocity\" \/>\n<meta property=\"og:url\" content=\"https:\/\/radiocityvalencia.es\/en\/artistas\/bearoid\/\" \/>\n<meta property=\"og:site_name\" content=\"Radiocity\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/radiocityvlc\" \/>\n<meta property=\"article:modified_time\" content=\"2023-10-30T13:03:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/radiocityvalencia.es\/wp-content\/uploads\/2023\/03\/MINIATURA-ARTISTAS-BEAROID.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"398\" \/>\n\t<meta property=\"og:image:height\" content=\"528\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/radiocityvalencia.es\\\/en\\\/artistas\\\/bearoid\\\/\",\"url\":\"https:\\\/\\\/radiocityvalencia.es\\\/en\\\/artistas\\\/bearoid\\\/\",\"name\":\"Bearoid - Radiocity\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/radiocityvalencia.es\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/radiocityvalencia.es\\\/en\\\/artistas\\\/bearoid\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/radiocityvalencia.es\\\/en\\\/artistas\\\/bearoid\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/radiocityvalencia.es\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/MINIATURA-ARTISTAS-BEAROID.webp\",\"datePublished\":\"2023-03-31T18:34:53+00:00\",\"dateModified\":\"2023-10-30T13:03:09+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/radiocityvalencia.es\\\/en\\\/artistas\\\/bearoid\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/radiocityvalencia.es\\\/en\\\/artistas\\\/bearoid\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/radiocityvalencia.es\\\/en\\\/artistas\\\/bearoid\\\/#primaryimage\",\"url\":\"https:\\\/\\\/radiocityvalencia.es\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/MINIATURA-ARTISTAS-BEAROID.webp\",\"contentUrl\":\"https:\\\/\\\/radiocityvalencia.es\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/MINIATURA-ARTISTAS-BEAROID.webp\",\"width\":398,\"height\":528},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/radiocityvalencia.es\\\/en\\\/artistas\\\/bearoid\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/radiocityvalencia.es\\\/en\\\/home\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Artistas\",\"item\":\"https:\\\/\\\/radiocityvalencia.es\\\/en\\\/artistas\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Bearoid\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/radiocityvalencia.es\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/radiocityvalencia.es\\\/en\\\/\",\"name\":\"Radio City Valencia\",\"description\":\"The Place to Be\",\"publisher\":{\"@id\":\"https:\\\/\\\/radiocityvalencia.es\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/radiocityvalencia.es\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/radiocityvalencia.es\\\/en\\\/#organization\",\"name\":\"Radio City Valencia\",\"url\":\"https:\\\/\\\/radiocityvalencia.es\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/radiocityvalencia.es\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/radiocityvalencia.es\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/LOGO_RADIO_WHT.png\",\"contentUrl\":\"https:\\\/\\\/radiocityvalencia.es\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/LOGO_RADIO_WHT.png\",\"width\":398,\"height\":57,\"caption\":\"Radio City Valencia\"},\"image\":{\"@id\":\"https:\\\/\\\/radiocityvalencia.es\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/radiocityvlc\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Bearoid - Radiocity","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/radiocityvalencia.es\/en\/artistas\/bearoid\/","og_locale":"en_US","og_type":"article","og_title":"Bearoid - Radiocity","og_url":"https:\/\/radiocityvalencia.es\/en\/artistas\/bearoid\/","og_site_name":"Radiocity","article_publisher":"https:\/\/www.facebook.com\/radiocityvlc","article_modified_time":"2023-10-30T13:03:09+00:00","og_image":[{"width":398,"height":528,"url":"https:\/\/radiocityvalencia.es\/wp-content\/uploads\/2023\/03\/MINIATURA-ARTISTAS-BEAROID.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/radiocityvalencia.es\/en\/artistas\/bearoid\/","url":"https:\/\/radiocityvalencia.es\/en\/artistas\/bearoid\/","name":"Bearoid - Radiocity","isPartOf":{"@id":"https:\/\/radiocityvalencia.es\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/radiocityvalencia.es\/en\/artistas\/bearoid\/#primaryimage"},"image":{"@id":"https:\/\/radiocityvalencia.es\/en\/artistas\/bearoid\/#primaryimage"},"thumbnailUrl":"https:\/\/radiocityvalencia.es\/wp-content\/uploads\/2023\/03\/MINIATURA-ARTISTAS-BEAROID.webp","datePublished":"2023-03-31T18:34:53+00:00","dateModified":"2023-10-30T13:03:09+00:00","breadcrumb":{"@id":"https:\/\/radiocityvalencia.es\/en\/artistas\/bearoid\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/radiocityvalencia.es\/en\/artistas\/bearoid\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/radiocityvalencia.es\/en\/artistas\/bearoid\/#primaryimage","url":"https:\/\/radiocityvalencia.es\/wp-content\/uploads\/2023\/03\/MINIATURA-ARTISTAS-BEAROID.webp","contentUrl":"https:\/\/radiocityvalencia.es\/wp-content\/uploads\/2023\/03\/MINIATURA-ARTISTAS-BEAROID.webp","width":398,"height":528},{"@type":"BreadcrumbList","@id":"https:\/\/radiocityvalencia.es\/en\/artistas\/bearoid\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/radiocityvalencia.es\/en\/home\/"},{"@type":"ListItem","position":2,"name":"Artistas","item":"https:\/\/radiocityvalencia.es\/en\/artistas\/"},{"@type":"ListItem","position":3,"name":"Bearoid"}]},{"@type":"WebSite","@id":"https:\/\/radiocityvalencia.es\/en\/#website","url":"https:\/\/radiocityvalencia.es\/en\/","name":"Radio City Valencia","description":"The Place to Be","publisher":{"@id":"https:\/\/radiocityvalencia.es\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/radiocityvalencia.es\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/radiocityvalencia.es\/en\/#organization","name":"Radio City Valencia","url":"https:\/\/radiocityvalencia.es\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/radiocityvalencia.es\/en\/#\/schema\/logo\/image\/","url":"https:\/\/radiocityvalencia.es\/wp-content\/uploads\/2023\/02\/LOGO_RADIO_WHT.png","contentUrl":"https:\/\/radiocityvalencia.es\/wp-content\/uploads\/2023\/02\/LOGO_RADIO_WHT.png","width":398,"height":57,"caption":"Radio City Valencia"},"image":{"@id":"https:\/\/radiocityvalencia.es\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/radiocityvlc"]}]}},"_links":{"self":[{"href":"https:\/\/radiocityvalencia.es\/en\/wp-json\/wp\/v2\/artistas\/1803","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/radiocityvalencia.es\/en\/wp-json\/wp\/v2\/artistas"}],"about":[{"href":"https:\/\/radiocityvalencia.es\/en\/wp-json\/wp\/v2\/types\/artistas"}],"author":[{"embeddable":true,"href":"https:\/\/radiocityvalencia.es\/en\/wp-json\/wp\/v2\/users\/2"}],"version-history":[{"count":4,"href":"https:\/\/radiocityvalencia.es\/en\/wp-json\/wp\/v2\/artistas\/1803\/revisions"}],"predecessor-version":[{"id":4106,"href":"https:\/\/radiocityvalencia.es\/en\/wp-json\/wp\/v2\/artistas\/1803\/revisions\/4106"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/radiocityvalencia.es\/en\/wp-json\/wp\/v2\/media\/1806"}],"wp:attachment":[{"href":"https:\/\/radiocityvalencia.es\/en\/wp-json\/wp\/v2\/media?parent=1803"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}